{"id":470,"date":"2022-07-04T22:19:05","date_gmt":"2022-07-05T02:19:05","guid":{"rendered":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/?p=470"},"modified":"2022-07-04T22:19:05","modified_gmt":"2022-07-05T02:19:05","slug":"la-semaine-des-langues-2022-par-mmes-jurin-et-fafard","status":"publish","type":"post","link":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/2022\/07\/04\/la-semaine-des-langues-2022-par-mmes-jurin-et-fafard\/","title":{"rendered":"La semaine des langues 2022 par Mmes Jurin et Fafard"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/__J0ES8YNig\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n\n\n\n<p>Du 4 au 8 avril 2022, la Semaine des langues vivantes a \u00e9t\u00e9 une occasion de plus de montrer au coll\u00e8ge de Basse Pointe l\u2019importance des langues et cultures dans la formation de nos \u00e9l\u00e8ves.<\/p>\n\n\n\n<p>Des \u00e9l\u00e8ves de 6\u00e8me et 5\u00e8me ont dessin\u00e9 et colori\u00e9 des drapeaux de pays europ\u00e9ens et ont r\u00e9alis\u00e9 un panneau \u201cBonsoir\/Bonne nuit\u201d avec les traductions en anglais et en espagnol .<\/p>\n\n\n\n<p>Des \u00e9l\u00e8ves de 4\u00e8me ont traduit le menu de la cantine en anglais, espagnol et portugais, ont compl\u00e9t\u00e9 en cr\u00e9ole, anglais et espagnol la signalisation au coll\u00e8ge et ont r\u00e9alis\u00e9 des panneaux ainsi qu\u2019un PowerPoint sur le football, le maquillage, le carnaval de Venise, celui de Sainte Lucie et celui du Br\u00e9sil en anglais, espagnol et fran\u00e7ais.<br>Des \u00e9l\u00e8ves de 3\u00e8me ont eux choisi entre autres, de pr\u00e9senter en anglais et fran\u00e7ais la gymnaste M\u00e9lanie de Jesus dos Santos.<\/p>\n\n\n\n<p>Par ailleurs, une exposition en fran\u00e7ais sur le Portugal, a \u00e9t\u00e9 r\u00e9alis\u00e9e avec des \u00e9l\u00e8ves de FLE (Fran\u00e7ais Langue Etrang\u00e8re). Un quiz accompagnait cette exposition.<\/p>\n\n\n\n<p>Les productions d\u2019\u00e9l\u00e8ves \u00e9taient visibles au CDI durant cette Semaine des langues.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Du 4 au 8 avril 2022, la Semaine des langues vivantes a \u00e9t\u00e9 une occasion de plus de montrer au coll\u00e8ge de Basse Pointe l\u2019importance des langues et cultures dans la formation de nos \u00e9l\u00e8ves. Des \u00e9l\u00e8ves de 6\u00e8me et 5\u00e8me ont dessin\u00e9 et colori\u00e9 des drapeaux de pays europ\u00e9ens et ont r\u00e9alis\u00e9 un panneau &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/2022\/07\/04\/la-semaine-des-langues-2022-par-mmes-jurin-et-fafard\/\" class=\"more-link\">Lire la suite de<span class=\"screen-reader-text\">\u00ab\u00a0La semaine des langues 2022 par Mmes Jurin et Fafard\u00a0\u00bb<\/span><\/a><\/p>\n","protected":false},"author":318,"featured_media":0,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-470","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":2,"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"predecessor-version":[{"id":472,"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/posts\/470\/revisions\/472"}],"wp:attachment":[{"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-bassepointe\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}