{"id":6567,"date":"2021-10-04T08:47:50","date_gmt":"2021-10-04T12:47:50","guid":{"rendered":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/?p=6567"},"modified":"2021-11-04T06:06:07","modified_gmt":"2021-11-04T10:06:07","slug":"assemblee-generale-de-rentree-des-parents-visioconference","status":"publish","type":"post","link":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/2021\/10\/04\/assemblee-generale-de-rentree-des-parents-visioconference\/","title":{"rendered":"ASSEMBLEE GENERALE DE RENTREE DES PARENTS (visioconf\u00e9rence)"},"content":{"rendered":"<p>Marin, le 30 \/09\/2021<br \/>\nLa principale<br \/>\nAux parents d\u2019\u00e9l\u00e8ves<br \/>\nObjet\u00a0: ASSEMBLEE GENERALE DE RENTREE DES PARENTS<br \/>\nChers parents,<br \/>\nVous \u00eates convi\u00e9s \u00e0 une r\u00e9union de rentr\u00e9e qui se d\u00e9roulera le jeudi 7 octobre \u00e0 17h30 en<br \/>\nvisioconf\u00e9rence<br \/>\nL\u2019ordre du jour sera le suivant\u00a0:<\/p>\n<p>&#8211; Point sur la rentr\u00e9e<br \/>\n&#8211; Pr\u00e9sentation des diff\u00e9rents services<br \/>\n&#8211; Elections des repr\u00e9sentants des parents au conseil d\u2019administration<br \/>\n&#8211; Pr\u00e9sentation de l\u2019association des parents d\u2019\u00e9l\u00e8ves<br \/>\n&#8211; Questions diverses<br \/>\nVeuillez vous connecter en utilisant le lien suivant :<\/p>\n<p><a href=\"https:\/\/visio-agents.education.fr\/meeting\/signin\/51699\/creator\/21856\/hash\/d96fddc25a6e4bc091b63744516052f0d7981c9e\">https:\/\/visio-agents.education.fr\/meeting\/signin\/51699\/creator\/21856\/hash\/d96fddc25a6e4bc091b63744516052f0d7981c9e<\/a><\/p>\n<p>Une fois connect\u00e9\u00a0: Mettre votre nom et cliquez sur rejoindre.<\/p>\n<p>Je vous remercie de votre collaboration.<br \/>\nEveline RETORY<br \/>\nPrincipale du coll\u00e8ge GERARD CAFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marin, le 30 \/09\/2021 La principale Aux parents d\u2019\u00e9l\u00e8ves Objet\u00a0: ASSEMBLEE GENERALE DE RENTREE DES <a class=\"continue-reading-link\" href=\"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/2021\/10\/04\/assemblee-generale-de-rentree-des-parents-visioconference\/\">lire plus <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":210,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"quote","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-6567","post","type-post","status-publish","format-quote","hentry","category-non-classe","post_format-post-format-quote"],"_links":{"self":[{"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/posts\/6567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/users\/210"}],"replies":[{"embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/comments?post=6567"}],"version-history":[{"count":1,"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/posts\/6567\/revisions"}],"predecessor-version":[{"id":6568,"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/posts\/6567\/revisions\/6568"}],"wp:attachment":[{"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/media?parent=6567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/categories?post=6567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site.ac-martinique.fr\/clg-gerardcafe\/wp-json\/wp\/v2\/tags?post=6567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}